
    <div class="bg-login-register"></div>
    

    <div class="custom-registration">

        <div class="header-login">
            <div class="texto-header">
                <div>
                    <h1 class="forms-login-title">Bienvenido</h1>
                    <div class="icono-header icono-mobile" style="display: none;">
                        <img src="/wp-content/plugins/client-area-planasa/assets/img/login-planasa.svg" class="imagen-forms" alt="Tu espacio Planasa" width="200" height="178">
                    </div>
                </div>
                <p class="forms-login-p">Para poder acceder a tu área de cliente, proporciona tu email de contacto.</p>
            </div>
            <div class="icono-header icono-desktop">
                <img src="/wp-content/plugins/client-area-planasa/assets/img/login-planasa.svg" class="imagen-forms" alt="Tu espacio Planasa" width="200" height="178">
            </div>
        </div>

        <form method="post" class="woocommerce-form woocommerce-form-register register"  >

                   	<p class="form-row form-row-wide cif-row">
			<label for="reg_cif">CIF de empresa <span class="required">*</span></label>
			<input type="text" class="input-text" name="cif" id="reg_cif" value=""  placeholder="CIF de empresa "/>
		</p>
		
            
            <p class="woocommerce-form-row woocommerce-form-row--wide form-row form-row-wide email-row">
                <label for="reg_email">Email&nbsp;<span class="required">*</span></label>
                <input type="email" class="woocommerce-Input woocommerce-Input--text input-text" placeholder="Email*" name="email" id="reg_email" autocomplete="email" value="" />            </p>

            
                <p class="woocommerce-form-row woocommerce-form-row--wide form-row form-row-wide password-row">
                    <label for="reg_password">Contraseña&nbsp;<span class="required">*</span></label>
                    <input type="password" placeholder="Contraseña*" class="woocommerce-Input woocommerce-Input--text input-text" name="password" id="reg_password" autocomplete="new-password" />
                </p>
                
            
            		<p class="form-row form-row-wide confirm-pass-row">
			<label for="reg_password2">Confirmar contraseña <span class="required">*</span></label>
	        <span class="password-input">
			    <input type="password" class="input-text" placeholder="Confirmar contraseña*" name="password2" id="reg_password2" value="" />
	        </span>
		</p>
		<wc-order-attribution-inputs></wc-order-attribution-inputs><div class="woocommerce-privacy-policy-text"><p>Tus datos personales se utilizarán para procesar tu pedido, mejorar tu experiencia en esta web, gestionar el acceso a tu cuenta y otros propósitos descritos en nuestra <a href="" class="woocommerce-privacy-policy-link" target="_blank">política de privacidad</a>.</p>
</div>            <div class="form-login-actions">

                <div class="inside-login">
                    <div class="no-registrado">¿Ya estás registrado? 
                        <a href="/es/mi-cuenta/" class="underline-link"><span class="word-underline-link">Iniciar sesión</span></a>
                    </div>
                    <div class="footer-login"><a href="#need-help" class="info-link-planasa custom-modal-link">¿Necesitas ayuda? <span class="acpl-info"></span></a></div>
                </div>
                <p class="woocommerce-form-row btn-submit-login text-align-right">
                    <input type="hidden" id="woocommerce-register-nonce" name="woocommerce-register-nonce" value="62a9f5173b" /><input type="hidden" name="_wp_http_referer" value="/es/wp-json/wp/v2/pages/13896" />                    <button type="submit" class="woocommerce-Button woocommerce-button button woocommerce-form-register__submit" name="register" value="Registro">Enviar</button>
                </p>
            </div>                       

            
        </form>
        <div class="custom-error-msg" style="display: none;">
            <div class="woocommerce-notices-wrapper"></div>        </div>
        <div class="under-login">
            <div class="no-registrado">¿Ya estás registrado? 
                <a href="/es/mi-cuenta/" class="underline-link"><span class="word-underline-link">Iniciar sesión</span></a>
            </div>
            <div class="footer-login"><a href="#need-help" class="info-link-planasa custom-modal-link">¿Necesitas ayuda? <span class="acpl-info"></span></a></div>
        </div>
        
    </div>

    
<div class="custom-modal modal-need-help" id="need-help">
	<div class="body-need-help">
		<div class="forms-login-title">¿Necesitas ayuda?</div>
		<p class="forms-login-p" style="width: 100% !important;">¿No consigues iniciar sesión o no recuerdas tus datos para acceder a tu Área de Cliente?</p>
		<p class="forms-login-p" style="width: 100% !important;">Facilítanos tu contacto y un experto de Planasa se pondrá en contacto contigo para resolver la incidencia.</p>
	</div>	
    <div class="woocommerce">
                <div class="frm_forms " id="frm_form_43_container" data-token="bfa5dbed5e5192b403b6c849c9664f06">
<form enctype="multipart/form-data" method="post" class="frm-show-form woocommerce-form frm_js_validate  frm_pro_form " id="form_clientareaneedhelpes" data-token="bfa5dbed5e5192b403b6c849c9664f06">
<div class="frm_form_fields ">
<fieldset>
<legend class="frm_screen_reader">Client area | need help | ES</legend>

<div class="frm_fields_container">
<input type="hidden" name="frm_action" value="create" />
<input type="hidden" name="form_id" value="43" />
<input type="hidden" name="frm_hide_fields_43" id="frm_hide_fields_43" value="" />
<input type="hidden" name="form_key" value="clientareaneedhelpes" />
<input type="hidden" name="item_meta[0]" value="" />
<input type="hidden" id="frm_submit_entry_43" name="frm_submit_entry_43" value="455ecfcda6" /><input type="hidden" name="_wp_http_referer" value="/es/wp-json/wp/v2/pages/13896" /><div id="frm_field_316_container" class="woocommerce-form-row woocommerce-form-row--wide form-row form-row-wide frm_form_field form-field  frm_required_field frm_top_container woocommerce-Input woocommerce-Input--text input-text ">
    <label for="field_n69li2" id="field_n69li2_label">Teléfono de contacto
        <span class="required" aria-hidden="true">*</span>
    </label>
    <input type="tel" id="field_n69li2" name="item_meta[316]" value=""  placeholder="Teléfono de contacto" data-reqmsg="Proporcione un número de teléfono" aria-required="true" data-invmsg="El teléfono no es válido" data-error-html="%3Cdiv+class%3D%22error+frm_error%22++id%3D%22frm_error_field_%5Bkey%5D%22%3E%3Cspan+class%3D%22acpl-warning%22+role%3D%22alert%22%3E%3C%2Fspan%3E+%5Berror%5D%3C%2Fdiv%3E" aria-invalid="false" pattern="((\+\d{1,3}(-|.| )?\(?\d\)?(-| |.)?\d{1,5})|(\(?\d{2,6}\)?))(-|.| )?(\d{3,4})(-|.| )?(\d{4})(( x| ext)\d{1,5}){0,1}$"  />
    
</div>
	<input type="hidden" name="item_key" value="" />
			<div id="frm_field_390_container">
			<label for="field_9qv1j" >
				Si eres humano, deja este campo en blanco.			</label>
			<input  id="field_9qv1j" type="text" class="frm_form_field form-field frm_verify" name="item_meta[390]" value=""  />
		</div>
		<input name="frm_state" type="hidden" value="dQWw6f3rmiszXAgKyUWpYsrhb7GhqQBb3eOWJRMwEGb8LxAQ0Cl134y2OgiKcIol" /><div class="form-row btn-submit-login text-align-right">
<button class="woocommerce-Button button" type="submit"   class="frm_final_submit">Enviar</button>
</div></div>
</fieldset>
</div>
<script type="text/javascript">var input = document.createElement('input');
    input.setAttribute('type', 'hidden');
    input.setAttribute('name', 'ct_checkjs_frm');
    input.setAttribute('value', 'b5ee4f95aa1e8f3693b9fb925cade2adb24602add1808fb6d8798f0fa2ffbbbd');
    for (i = 0; i < document.forms.length; i++) {
        if (typeof document.forms[i].id == 'string'){
			if(document.forms[i].id.search('form_clientareaneedhelpes') != -1) {
            document.forms[i].appendChild(input);
			}
        }
    }</script>

</form>
</div>
    </div>

</div>    <div class="bg-login-register"></div>
    

    <div class="custom-registration">

        <div class="header-login">
            <div class="texto-header">
                <div>
                    <h1 class="forms-login-title">Bienvenido</h1>
                    <div class="icono-header icono-mobile" style="display: none;">
                        <img src="/wp-content/plugins/client-area-planasa/assets/img/login-planasa.svg" class="imagen-forms" alt="Tu espacio Planasa" width="200" height="178">
                    </div>
                </div>
                <p class="forms-login-p">Para poder acceder a tu área de cliente, proporciona tu email de contacto.</p>
            </div>
            <div class="icono-header icono-desktop">
                <img src="/wp-content/plugins/client-area-planasa/assets/img/login-planasa.svg" class="imagen-forms" alt="Tu espacio Planasa" width="200" height="178">
            </div>
        </div>

        <form method="post" class="woocommerce-form woocommerce-form-register register"  >

                   	<p class="form-row form-row-wide cif-row">
			<label for="reg_cif">CIF de empresa <span class="required">*</span></label>
			<input type="text" class="input-text" name="cif" id="reg_cif" value=""  placeholder="CIF de empresa "/>
		</p>
		
            
            <p class="woocommerce-form-row woocommerce-form-row--wide form-row form-row-wide email-row">
                <label for="reg_email">Email&nbsp;<span class="required">*</span></label>
                <input type="email" class="woocommerce-Input woocommerce-Input--text input-text" placeholder="Email*" name="email" id="reg_email" autocomplete="email" value="" />            </p>

            
                <p class="woocommerce-form-row woocommerce-form-row--wide form-row form-row-wide password-row">
                    <label for="reg_password">Contraseña&nbsp;<span class="required">*</span></label>
                    <input type="password" placeholder="Contraseña*" class="woocommerce-Input woocommerce-Input--text input-text" name="password" id="reg_password" autocomplete="new-password" />
                </p>
                
            
            		<p class="form-row form-row-wide confirm-pass-row">
			<label for="reg_password2">Confirmar contraseña <span class="required">*</span></label>
	        <span class="password-input">
			    <input type="password" class="input-text" placeholder="Confirmar contraseña*" name="password2" id="reg_password2" value="" />
	        </span>
		</p>
		<wc-order-attribution-inputs></wc-order-attribution-inputs><div class="woocommerce-privacy-policy-text"><p>Tus datos personales se utilizarán para procesar tu pedido, mejorar tu experiencia en esta web, gestionar el acceso a tu cuenta y otros propósitos descritos en nuestra <a href="" class="woocommerce-privacy-policy-link" target="_blank">política de privacidad</a>.</p>
</div>            <div class="form-login-actions">

                <div class="inside-login">
                    <div class="no-registrado">¿Ya estás registrado? 
                        <a href="/es/mi-cuenta/" class="underline-link"><span class="word-underline-link">Iniciar sesión</span></a>
                    </div>
                    <div class="footer-login"><a href="#need-help" class="info-link-planasa custom-modal-link">¿Necesitas ayuda? <span class="acpl-info"></span></a></div>
                </div>
                <p class="woocommerce-form-row btn-submit-login text-align-right">
                    <input type="hidden" id="woocommerce-register-nonce" name="woocommerce-register-nonce" value="62a9f5173b" /><input type="hidden" name="_wp_http_referer" value="/es/wp-json/wp/v2/pages/13896" />                    <button type="submit" class="woocommerce-Button woocommerce-button button woocommerce-form-register__submit" name="register" value="Registro">Enviar</button>
                </p>
            </div>                       

            
        </form>
        <div class="custom-error-msg" style="display: none;">
            <div class="woocommerce-notices-wrapper"></div>        </div>
        <div class="under-login">
            <div class="no-registrado">¿Ya estás registrado? 
                <a href="/es/mi-cuenta/" class="underline-link"><span class="word-underline-link">Iniciar sesión</span></a>
            </div>
            <div class="footer-login"><a href="#need-help" class="info-link-planasa custom-modal-link">¿Necesitas ayuda? <span class="acpl-info"></span></a></div>
        </div>
        
    </div>

    
<div class="custom-modal modal-need-help" id="need-help">
	<div class="body-need-help">
		<div class="forms-login-title">¿Necesitas ayuda?</div>
		<p class="forms-login-p" style="width: 100% !important;">¿No consigues iniciar sesión o no recuerdas tus datos para acceder a tu Área de Cliente?</p>
		<p class="forms-login-p" style="width: 100% !important;">Facilítanos tu contacto y un experto de Planasa se pondrá en contacto contigo para resolver la incidencia.</p>
	</div>	
    <div class="woocommerce">
                <div class="frm_forms " id="frm_form_43_container" data-token="bfa5dbed5e5192b403b6c849c9664f06" data-token="bfa5dbed5e5192b403b6c849c9664f06">
<form enctype="multipart/form-data" method="post" class="frm-show-form woocommerce-form frm_js_validate  frm_pro_form " id="form_clientareaneedhelpes" data-token="bfa5dbed5e5192b403b6c849c9664f06" data-token="bfa5dbed5e5192b403b6c849c9664f06">
<div class="frm_form_fields ">
<fieldset>
<legend class="frm_screen_reader">Client area | need help | ES</legend>

<div class="frm_fields_container">
<input type="hidden" name="frm_action" value="create" />
<input type="hidden" name="form_id" value="43" />
<input type="hidden" name="frm_hide_fields_43" id="frm_hide_fields_43" value="" />
<input type="hidden" name="form_key" value="clientareaneedhelpes" />
<input type="hidden" name="item_meta[0]" value="" />
<input type="hidden" id="frm_submit_entry_43" name="frm_submit_entry_43" value="455ecfcda6" /><input type="hidden" name="_wp_http_referer" value="/es/wp-json/wp/v2/pages/13896" /><div id="frm_field_316_container" class="woocommerce-form-row woocommerce-form-row--wide form-row form-row-wide frm_form_field form-field  frm_required_field frm_top_container woocommerce-Input woocommerce-Input--text input-text ">
    <label for="field_n69li2" id="field_n69li2_label">Teléfono de contacto
        <span class="required" aria-hidden="true">*</span>
    </label>
    <input type="tel" id="field_n69li2" name="item_meta[316]" value=""  placeholder="Teléfono de contacto" data-reqmsg="Proporcione un número de teléfono" aria-required="true" data-invmsg="El teléfono no es válido" data-error-html="%3Cdiv+class%3D%22error+frm_error%22++id%3D%22frm_error_field_%5Bkey%5D%22%3E%3Cspan+class%3D%22acpl-warning%22+role%3D%22alert%22%3E%3C%2Fspan%3E+%5Berror%5D%3C%2Fdiv%3E" aria-invalid="false" pattern="((\+\d{1,3}(-|.| )?\(?\d\)?(-| |.)?\d{1,5})|(\(?\d{2,6}\)?))(-|.| )?(\d{3,4})(-|.| )?(\d{4})(( x| ext)\d{1,5}){0,1}$"  />
    
</div>
	<input type="hidden" name="item_key" value="" />
			<div id="frm_field_391_container">
			<label for="field_fmpzs" >
				Si eres humano, deja este campo en blanco.			</label>
			<input  id="field_fmpzs" type="text" class="frm_form_field form-field frm_verify" name="item_meta[391]" value=""  />
		</div>
		<input name="frm_state" type="hidden" value="dQWw6f3rmiszXAgKyUWpYsrhb7GhqQBb3eOWJRMwEGZJjf1yt9BcVBD5i5hLrVMw" /><div class="form-row btn-submit-login text-align-right">
<button class="woocommerce-Button button" type="submit"   class="frm_final_submit">Enviar</button>
</div></div>
</fieldset>
</div>
<script type="text/javascript">var input = document.createElement('input');
    input.setAttribute('type', 'hidden');
    input.setAttribute('name', 'ct_checkjs_frm');
    input.setAttribute('value', 'b5ee4f95aa1e8f3693b9fb925cade2adb24602add1808fb6d8798f0fa2ffbbbd');
    for (i = 0; i < document.forms.length; i++) {
        if (typeof document.forms[i].id == 'string'){
			if(document.forms[i].id.search('form_clientareaneedhelpes') != -1) {
            document.forms[i].appendChild(input);
			}
        }
    }</script>

</form>
</div>
    </div>

</div>{"id":13896,"date":"2022-10-28T11:42:07","date_gmt":"2022-10-28T11:42:07","guid":{"rendered":"http:\/\/localhost\/planasa.com\/registration\/"},"modified":"2022-10-28T11:44:22","modified_gmt":"2022-10-28T11:44:22","slug":"registration","status":"publish","type":"page","link":"https:\/\/planasa.com\/es\/registration\/","title":{"rendered":"Registration"},"content":{"rendered":"\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-auth.php","meta":{"footnotes":""},"class_list":["post-13896","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Registration - Planasa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/planasa.com\/es\/registration\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Registration - Planasa\" \/>\n<meta property=\"og:url\" content=\"https:\/\/planasa.com\/es\/registration\/\" \/>\n<meta property=\"og:site_name\" content=\"Planasa\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-28T11:44:22+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/planasa.com\\\/es\\\/registration\\\/\",\"url\":\"https:\\\/\\\/planasa.com\\\/es\\\/registration\\\/\",\"name\":\"Registration - Planasa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/planasa.com\\\/es\\\/#website\"},\"datePublished\":\"2022-10-28T11:42:07+00:00\",\"dateModified\":\"2022-10-28T11:44:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/planasa.com\\\/es\\\/registration\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/planasa.com\\\/es\\\/registration\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/planasa.com\\\/es\\\/registration\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/planasa.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Registration\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/planasa.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/planasa.com\\\/es\\\/\",\"name\":\"Planasa\",\"description\":\"Innovation in plant varieties\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/planasa.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Registration - Planasa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/planasa.com\/es\/registration\/","og_locale":"es_ES","og_type":"article","og_title":"Registration - Planasa","og_url":"https:\/\/planasa.com\/es\/registration\/","og_site_name":"Planasa","article_modified_time":"2022-10-28T11:44:22+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/planasa.com\/es\/registration\/","url":"https:\/\/planasa.com\/es\/registration\/","name":"Registration - Planasa","isPartOf":{"@id":"https:\/\/planasa.com\/es\/#website"},"datePublished":"2022-10-28T11:42:07+00:00","dateModified":"2022-10-28T11:44:22+00:00","breadcrumb":{"@id":"https:\/\/planasa.com\/es\/registration\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/planasa.com\/es\/registration\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/planasa.com\/es\/registration\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/planasa.com\/es\/"},{"@type":"ListItem","position":2,"name":"Registration"}]},{"@type":"WebSite","@id":"https:\/\/planasa.com\/es\/#website","url":"https:\/\/planasa.com\/es\/","name":"Planasa","description":"Innovation in plant varieties","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/planasa.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/planasa.com\/es\/wp-json\/wp\/v2\/pages\/13896","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/planasa.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/planasa.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/planasa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/planasa.com\/es\/wp-json\/wp\/v2\/comments?post=13896"}],"version-history":[{"count":0,"href":"https:\/\/planasa.com\/es\/wp-json\/wp\/v2\/pages\/13896\/revisions"}],"wp:attachment":[{"href":"https:\/\/planasa.com\/es\/wp-json\/wp\/v2\/media?parent=13896"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}